{"id":47267,"date":"2019-02-25T08:56:12","date_gmt":"2019-02-25T07:56:12","guid":{"rendered":"https:\/\/www.icaib.org\/?p=47267"},"modified":"2019-02-25T08:57:09","modified_gmt":"2019-02-25T07:57:09","slug":"lobertura-del-periode-dinscripcio-a-cadascuna-delles-savisara-com-ja-es-habitual-per-circular","status":"publish","type":"post","link":"https:\/\/www.icaib.org\/ca\/lobertura-del-periode-dinscripcio-a-cadascuna-delles-savisara-com-ja-es-habitual-per-circular\/","title":{"rendered":"L&#8217;obertura del per\u00edode d&#8217;inscripci\u00f3 a cadascuna d&#8217;elles s&#8217;avisar\u00e0, com ja \u00e9s habitual, per circular."},"content":{"rendered":"<p><strong>17 de mar\u00e7. Cam\u00ed de l&#8217;Arxiduc<\/strong><br \/>\nExcursi\u00f3 de 12 quil\u00f2metres i d&#8217;unes cinc hores de durada, de nivell f\u00e0cil \/ mig i circular.<br \/>\nDesnivell: 570 metres de pujada i 570 de baixada aproximadament.<br \/>\nHora i punt de trobada: A les 9.30 hores al carrer \u00c0ustria de Valldemossa.<\/p>\n<p><strong>21 d&#8217;abril. Cim del Puig de Massanella.<\/strong><br \/>\nExcursi\u00f3 de 14 quil\u00f2metres i set hores de durada, de nivell mitj\u00e0 \/ alt.<br \/>\nDesnivell: 800 metres de pujada i 800 de baixada.<br \/>\nAl\u00e7ada m\u00e0xima: 1.365 metres.<br \/>\nHora i punt de trobada: A les 9.00 hores a l&#8217;aparcament de la font des Noguer (Escorca) km 33.7 de la carretera Andratx Pollen\u00e7a (MA-10).<\/p>\n<p><strong>19 de maig. Cal\u00f3 de s&#8217;Estaca i Sa Foradada<\/strong><br \/>\nExcursi\u00f3 de 13 quil\u00f2metres, de nivell mitj\u00e0 i una durada aproximada de set hores.<br \/>\nDesnivell: 610 metres de pujada i 690 de baixada.<br \/>\nHora i punt de trobada: A les 9:00 hores a l&#8217;aparcament de Son Marroig (Sa foradada).<\/p>\n<p><strong>16 de juny. La Trapa.<\/strong><br \/>\nExcursi\u00f3 de 11 quil\u00f2metres, cinc hores de durada i nivell f\u00e0cil.<br \/>\nDesnivell: 400 metres de pujada i 400 de baixada aproximadament.<br \/>\nHora i punt de trobada: A les 9.30 hores a la pla\u00e7a Moss\u00e8n Sebasti\u00e0 Grau (Sant Elm)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>17 de mar\u00e7. Cam\u00ed de l&#8217;Arxiduc Excursi\u00f3 de 12 quil\u00f2metres  [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":47265,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[],"class_list":["post-47267","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticies-icaib"],"_links":{"self":[{"href":"https:\/\/www.icaib.org\/ca\/wp-json\/wp\/v2\/posts\/47267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.icaib.org\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.icaib.org\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.icaib.org\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.icaib.org\/ca\/wp-json\/wp\/v2\/comments?post=47267"}],"version-history":[{"count":0,"href":"https:\/\/www.icaib.org\/ca\/wp-json\/wp\/v2\/posts\/47267\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.icaib.org\/ca\/wp-json\/wp\/v2\/media\/47265"}],"wp:attachment":[{"href":"https:\/\/www.icaib.org\/ca\/wp-json\/wp\/v2\/media?parent=47267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.icaib.org\/ca\/wp-json\/wp\/v2\/categories?post=47267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.icaib.org\/ca\/wp-json\/wp\/v2\/tags?post=47267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}